{"id":862,"date":"2015-11-02T02:11:41","date_gmt":"2015-11-01T23:11:41","guid":{"rendered":"https:\/\/dau.edu.sa\/?page_id=862&#038;lang=en"},"modified":"2018-02-26T00:59:54","modified_gmt":"2018-02-25T21:59:54","slug":"provost-letter","status":"publish","type":"page","link":"https:\/\/dau.edu.sa\/en\/provost-letter\/","title":{"rendered":"Dean&#8217;s Letter"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"page-agencies.php","meta":{"nf_dc_page":"","footnotes":""},"class_list":["post-862","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/dau.edu.sa\/en\/wp-json\/wp\/v2\/pages\/862","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dau.edu.sa\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/dau.edu.sa\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/dau.edu.sa\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dau.edu.sa\/en\/wp-json\/wp\/v2\/comments?post=862"}],"version-history":[{"count":0,"href":"https:\/\/dau.edu.sa\/en\/wp-json\/wp\/v2\/pages\/862\/revisions"}],"wp:attachment":[{"href":"https:\/\/dau.edu.sa\/en\/wp-json\/wp\/v2\/media?parent=862"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}